{"id":4947,"date":"2024-01-07T20:13:56","date_gmt":"2024-01-07T19:13:56","guid":{"rendered":"https:\/\/tempelherrenorden.de\/cms\/?p=4947"},"modified":"2024-01-07T21:41:40","modified_gmt":"2024-01-07T20:41:40","slug":"trauermeldung-des-deutschen-tempelherren-orden","status":"publish","type":"post","link":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/","title":{"rendered":"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Unsere liebe Ordensschwester Irmgard Richter, Ordensdame Komturei St. Georg, ist am 07.12.2023 friedlich im Krankenhaus in Cottbus verstorben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein letzter Wunsch von Osr. Irmgard war, \u201ewieder bei ihrer Familie zu sein\u201c.<br \/>Der Verstorbenen gilt unser stilles Gebet und den Angeh\u00f6rigen unsere Anteilnahme.<br \/>M\u00f6ge unsere Ordensschwester in Frieden ruhen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">NON NOBIS DOMINE<br \/>Ordensregierung DTHO\/OMCT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere liebe Ordensschwester Irmgard Richter, Ordensdame Komturei St. Georg, ist am 07.12.2023 friedlich im Krankenhaus in Cottbus verstorben. Ein letzter Wunsch von Osr. Irmgard war, \u201ewieder bei ihrer Familie zu sein\u201c.Der Verstorbenen gilt unser stilles Gebet und den Angeh\u00f6rigen unsere Anteilnahme.M\u00f6ge unsere Ordensschwester in Frieden ruhen. NON NOBIS DOMINEOrdensregierung DTHO\/OMCT<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/\"><span>Artikel lesen<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":10,"featured_media":2805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,37,73],"tags":[52,49,50,63,45,44],"class_list":["post-4947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-georg","category-nachruf","tag-berlin","tag-komturei","tag-st-georg","tag-tempelherren","tag-tempelritter","tag-templer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN &#8226; Deutscher Tempelherren-Orden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN &#8226; Deutscher Tempelherren-Orden\" \/>\n<meta property=\"og:description\" content=\"Unsere liebe Ordensschwester Irmgard Richter, Ordensdame Komturei St. Georg, ist am 07.12.2023 friedlich im Krankenhaus in Cottbus verstorben. Ein letzter Wunsch von Osr. Irmgard war, \u201ewieder bei ihrer Familie zu sein\u201c.Der Verstorbenen gilt unser stilles Gebet und den Angeh\u00f6rigen unsere Anteilnahme.M\u00f6ge unsere Ordensschwester in Frieden ruhen. NON NOBIS DOMINEOrdensregierung DTHO\/OMCT Artikel lesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutscher Tempelherren-Orden\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deutscher-Tempelherren-Orden-OMCT-2054469481490772\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-07T19:13:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-07T20:41:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#\\\/schema\\\/person\\\/c4b556c7412791f0ed2d6851086be4aa\"},\"headline\":\"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN\",\"datePublished\":\"2024-01-07T19:13:56+00:00\",\"dateModified\":\"2024-01-07T20:41:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/\"},\"wordCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/tempelherrenorden.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Templer_06.jpg?fit=400%2C327&ssl=1\",\"keywords\":[\"Berlin\",\"Komturei\",\"St. Georg\",\"Tempelherren\",\"Tempelritter\",\"Templer\"],\"articleSection\":{\"1\":\"Komturei St. Georg\",\"2\":\"Nachruf\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/\",\"url\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/\",\"name\":\"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN &#8226; Deutscher Tempelherren-Orden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/tempelherrenorden.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Templer_06.jpg?fit=400%2C327&ssl=1\",\"datePublished\":\"2024-01-07T19:13:56+00:00\",\"dateModified\":\"2024-01-07T20:41:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/tempelherrenorden.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Templer_06.jpg?fit=400%2C327&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/tempelherrenorden.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Templer_06.jpg?fit=400%2C327&ssl=1\",\"width\":400,\"height\":327},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/trauermeldung-des-deutschen-tempelherren-orden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/\",\"name\":\"Deutscher Tempelherren-Orden\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#organization\",\"name\":\"Deutscher Tempelherren-Orden OMCT e.V.\",\"url\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/tempelherrenorden.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/OMCT-Wappen.jpg?fit=997%2C1198&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/tempelherrenorden.de\\\/cms\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/OMCT-Wappen.jpg?fit=997%2C1198&ssl=1\",\"width\":997,\"height\":1198,\"caption\":\"Deutscher Tempelherren-Orden OMCT e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deutscher-Tempelherren-Orden-OMCT-2054469481490772\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/#\\\/schema\\\/person\\\/c4b556c7412791f0ed2d6851086be4aa\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ed839132852af2d0905f18562e70ba28d4d5c2fa1196284813995a27f534319?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ed839132852af2d0905f18562e70ba28d4d5c2fa1196284813995a27f534319?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ed839132852af2d0905f18562e70ba28d4d5c2fa1196284813995a27f534319?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"url\":\"https:\\\/\\\/tempelherrenorden.de\\\/cms\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN &#8226; Deutscher Tempelherren-Orden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/","og_locale":"de_DE","og_type":"article","og_title":"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN &#8226; Deutscher Tempelherren-Orden","og_description":"Unsere liebe Ordensschwester Irmgard Richter, Ordensdame Komturei St. Georg, ist am 07.12.2023 friedlich im Krankenhaus in Cottbus verstorben. Ein letzter Wunsch von Osr. Irmgard war, \u201ewieder bei ihrer Familie zu sein\u201c.Der Verstorbenen gilt unser stilles Gebet und den Angeh\u00f6rigen unsere Anteilnahme.M\u00f6ge unsere Ordensschwester in Frieden ruhen. NON NOBIS DOMINEOrdensregierung DTHO\/OMCT Artikel lesen","og_url":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/","og_site_name":"Deutscher Tempelherren-Orden","article_publisher":"https:\/\/www.facebook.com\/Deutscher-Tempelherren-Orden-OMCT-2054469481490772\/","article_published_time":"2024-01-07T19:13:56+00:00","article_modified_time":"2024-01-07T20:41:40+00:00","og_image":[{"width":400,"height":327,"url":"https:\/\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#article","isPartOf":{"@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/"},"author":{"name":"Redaktion","@id":"https:\/\/tempelherrenorden.de\/cms\/#\/schema\/person\/c4b556c7412791f0ed2d6851086be4aa"},"headline":"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN","datePublished":"2024-01-07T19:13:56+00:00","dateModified":"2024-01-07T20:41:40+00:00","mainEntityOfPage":{"@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/"},"wordCount":58,"publisher":{"@id":"https:\/\/tempelherrenorden.de\/cms\/#organization"},"image":{"@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg?fit=400%2C327&ssl=1","keywords":["Berlin","Komturei","St. Georg","Tempelherren","Tempelritter","Templer"],"articleSection":{"1":"Komturei St. Georg","2":"Nachruf"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/","url":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/","name":"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN &#8226; Deutscher Tempelherren-Orden","isPartOf":{"@id":"https:\/\/tempelherrenorden.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#primaryimage"},"image":{"@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg?fit=400%2C327&ssl=1","datePublished":"2024-01-07T19:13:56+00:00","dateModified":"2024-01-07T20:41:40+00:00","breadcrumb":{"@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#primaryimage","url":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg?fit=400%2C327&ssl=1","contentUrl":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg?fit=400%2C327&ssl=1","width":400,"height":327},{"@type":"BreadcrumbList","@id":"https:\/\/tempelherrenorden.de\/cms\/trauermeldung-des-deutschen-tempelherren-orden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tempelherrenorden.de\/cms\/"},{"@type":"ListItem","position":2,"name":"TRAUERMELDUNG DES DEUTSCHEN TEMPELHERREN-ORDEN"}]},{"@type":"WebSite","@id":"https:\/\/tempelherrenorden.de\/cms\/#website","url":"https:\/\/tempelherrenorden.de\/cms\/","name":"Deutscher Tempelherren-Orden","description":"","publisher":{"@id":"https:\/\/tempelherrenorden.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tempelherrenorden.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tempelherrenorden.de\/cms\/#organization","name":"Deutscher Tempelherren-Orden OMCT e.V.","url":"https:\/\/tempelherrenorden.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tempelherrenorden.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/01\/OMCT-Wappen.jpg?fit=997%2C1198&ssl=1","contentUrl":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/01\/OMCT-Wappen.jpg?fit=997%2C1198&ssl=1","width":997,"height":1198,"caption":"Deutscher Tempelherren-Orden OMCT e.V."},"image":{"@id":"https:\/\/tempelherrenorden.de\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deutscher-Tempelherren-Orden-OMCT-2054469481490772\/"]},{"@type":"Person","@id":"https:\/\/tempelherrenorden.de\/cms\/#\/schema\/person\/c4b556c7412791f0ed2d6851086be4aa","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4ed839132852af2d0905f18562e70ba28d4d5c2fa1196284813995a27f534319?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ed839132852af2d0905f18562e70ba28d4d5c2fa1196284813995a27f534319?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ed839132852af2d0905f18562e70ba28d4d5c2fa1196284813995a27f534319?s=96&d=mm&r=g","caption":"Redaktion"},"url":"https:\/\/tempelherrenorden.de\/cms\/author\/redaktion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/tempelherrenorden.de\/cms\/wp-content\/uploads\/2018\/09\/Templer_06.jpg?fit=400%2C327&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p5yQvL-1hN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/posts\/4947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/comments?post=4947"}],"version-history":[{"count":2,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/posts\/4947\/revisions"}],"predecessor-version":[{"id":4949,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/posts\/4947\/revisions\/4949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/media\/2805"}],"wp:attachment":[{"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/media?parent=4947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/categories?post=4947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tempelherrenorden.de\/cms\/wp-json\/wp\/v2\/tags?post=4947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}